{"id":42034,"date":"2022-08-18T11:03:52","date_gmt":"2022-08-18T16:03:52","guid":{"rendered":"https:\/\/kmy.website\/?p=42034"},"modified":"2023-07-21T17:09:13","modified_gmt":"2023-07-21T22:09:13","slug":"whole-shop-bundle-en","status":"publish","type":"post","link":"https:\/\/kmy.website\/en\/whole-shop-bundle-en\/","title":{"rendered":"Keikoya Whole Shop Design Bundle &#8211; 3800+ Canva Templates &#038; Free Update"},"content":{"rendered":"\n<h2 class=\"wp-block-heading is-style-section_ttl\">Keikoya Whole Shop Design Bundle &ndash; 3800+ Canva Templates &amp; Free Update<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Get&nbsp;<strong>over $900 worth<\/strong>&nbsp;of Keikoya&rsquo;s entire 3800+ Canva templates, elements, and more for only&nbsp;<strong>$109<\/strong>, saving over $800! <br>Purchase today and you will get <strong>all the future updates for free!<\/strong><\/p>\n\n\n\n<div class=\"swell-block-button red_ is-style-btn_shiny u-mb-ctrl u-mb-30\" data-id=\"c4c93406\"><a href=\"https:\/\/keikoya.gumroad.com\/l\/WholeShopBundle?a=389461075\" target=\"_blank\" rel=\"noopener nofollow\" class=\"swell-block-button__link\" data-has-icon=\"1\"><span>BUY DEAL NOW<\/span><svg class=\"__icon -right\" height=\"1em\" width=\"1em\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" viewbox=\"0 0 448 512\"><path d=\"M438.6 278.6c12.5-12.5 12.5-32.8 0-45.3l-160-160c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3L338.8 224 32 224c-17.7 0-32 14.3-32 32s14.3 32 32 32l306.7 0L233.4 393.4c-12.5 12.5-12.5 32.8 0 45.3s32.8 12.5 45.3 0l160-160z\"><\/path><\/svg><\/a><\/div>\n\n\n\n<h3 class=\"wp-block-heading is-style-section_ttl\">Social Media Template Pack<\/h3>\n\n\n<div class=\"p-postListWrap\"><ul class=\"p-postList -type-card -pc-col3 -sp-col1\"><li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-story-hand-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/20-IG-PostStory-Presentation-43.jpg\" alt=\"300 Instagram Templates Canva Post Story Hand\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/20-IG-PostStory-Presentation-43.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/20-IG-PostStory-Presentation-43-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/20-IG-PostStory-Presentation-43-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/20-IG-PostStory-Presentation-43.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">300 Instagram Templates Canva Post Story Hand<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-story-zen-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Zen-1.jpg\" alt=\"Instagram Template Canva Post Story Zen - Clean Minimum Business Animated Social Media Bundle\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Zen-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Zen-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Zen-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Zen-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Post Story Zen &ndash; Clean Minimum Business Animated Social Media Bundle<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-pinterest-templates-canva-glass-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Pinterest-Template-Canva-glass1-1024x683.jpg\" alt=\"288 Instagram &amp; Pinterest Template Canva Post Story Glass - Social Media Motivational Quote Pack\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Pinterest-Template-Canva-glass1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Pinterest-Template-Canva-glass1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Pinterest-Template-Canva-glass1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Pinterest-Template-Canva-glass1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Pinterest-Template-Canva-glass1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Pinterest-Template-Canva-glass1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">288 Instagram &amp; Pinterest Template Canva Post Story Glass &ndash; Social Media Motivational Quote Pack&#65532;<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-story-luxe-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Luxe-1-1024x683.jpg\" alt=\"300 Instagram Template Canva Post Story Luxe - Carousel Animated Social Media Cover Pack - Quotes, Notification, CTA\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Luxe-1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Luxe-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Luxe-1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Luxe-1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Luxe-1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Luxe-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">300+ Instagram Templates Canva Post Story Luxe &ndash; Carousel Animated Social Media Cover Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-pinterest-templates-canva-wabi-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-pinterest-carousel-templates-canva1-1024x683.jpg\" alt=\"500 Instagram Pinterest Template Canva Wabi-sabi - Post Story Reel Idea Pin Cover Animated Social Media Bundle\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-pinterest-carousel-templates-canva1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-pinterest-carousel-templates-canva1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-pinterest-carousel-templates-canva1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-pinterest-carousel-templates-canva1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-pinterest-carousel-templates-canva1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-pinterest-carousel-templates-canva1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">500 Instagram Pinterest Template Canva Wabi-sabi &ndash; Post Story Reel Idea Pin Cover Animated Social Media Bundle<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-post-story-template-pack-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-and-Story-templates1.jpg\" alt=\"Instagram Post and Story templates\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-and-Story-templates1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-and-Story-templates1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-and-Story-templates1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-and-Story-templates1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Post Story &ndash; Minimum Carousel Social Media Pack &ndash; Quotes, Notification<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-post-story-template-dot-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-story-template-dot-1-2-1024x683.jpg\" alt=\"Instagram Template Post Story Canva Polka Dot - Reel Carousel Animated Social Media Pack - Quotes, Notification, CTA\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-story-template-dot-1-2-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-story-template-dot-1-2-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-story-template-dot-1-2-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-story-template-dot-1-2-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-story-template-dot-1-2.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-story-template-dot-1-2.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Post Story templates Canva Polka Dot<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-story-shine-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shine-1.jpg\" alt=\"Instagram Template Canva Post Story Shine - Reel Shorts Carousel Animated Social Media Pack - Quotes, Notification, CTA\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shine-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shine-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shine-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shine-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Post Story Shine &ndash; Reel Shorts Animated Social Media Pack &ndash; Quotes, Notification, CTA<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-story-mint-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Mint-1-1024x683.jpg\" alt=\"Instagram Template Canva Post Story Mint - Reel Cover Carousel Animated Social Media Pack - Quotes, Notification, CTA\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Mint-1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Mint-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Mint-1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Mint-1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Mint-1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Mint-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Post Story Mint &ndash; Reel Cover Carousel Animated Social Media Pack &ndash; Quotes, Notification, CTA<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-post-story-template-shadow-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shadow-1-1-1024x683.jpg\" alt=\"Instagram Template Canva Post Story Shadow\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shadow-1-1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shadow-1-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shadow-1-1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shadow-1-1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shadow-1-1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Story-Shadow-1-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">300 Instagram Templates Canva Post Story Shadow<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-post-story-template-calendar-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Story-templates-Canva-Calendar-anime-1-1024x683.jpg\" alt=\"Instagram Template Canva Post Story Calendar - Reel Carousel Animated Cover Social Media Pack - Quotes, Notification, CTA\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Story-templates-Canva-Calendar-anime-1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Story-templates-Canva-Calendar-anime-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Story-templates-Canva-Calendar-anime-1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Story-templates-Canva-Calendar-anime-1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Story-templates-Canva-Calendar-anime-1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Story-templates-Canva-Calendar-anime-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Post Story Canva Calendar &ndash; Editable Reel Shorts Pinterest Idea Pins Animated Social Media Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<\/ul><\/div>\n\n\n<div class=\"swell-block-button red_ is-style-btn_shiny u-mb-ctrl u-mb-30\" data-id=\"b439fd60\"><a href=\"https:\/\/keikoya.gumroad.com\/l\/WholeShopBundle?a=389461075\" target=\"_blank\" rel=\"noopener nofollow\" class=\"swell-block-button__link\" data-has-icon=\"1\"><span>BUY DEAL NOW<\/span><svg class=\"__icon -right\" height=\"1em\" width=\"1em\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" viewbox=\"0 0 448 512\"><path d=\"M438.6 278.6c12.5-12.5 12.5-32.8 0-45.3l-160-160c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3L338.8 224 32 224c-17.7 0-32 14.3-32 32s14.3 32 32 32l306.7 0L233.4 393.4c-12.5 12.5-12.5 32.8 0 45.3s32.8 12.5 45.3 0l160-160z\"><\/path><\/svg><\/a><\/div>\n\n\n\n<h3 class=\"wp-block-heading is-style-section_ttl\">Instagram Templates<\/h3>\n\n\n<div class=\"p-postListWrap\"><ul class=\"p-postList -type-card -pc-col3 -sp-col1\"><li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-sun-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Sun-1-1024x683.jpg\" alt=\"Instagram Template Canva Post Sun\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Sun-1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Sun-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Sun-1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Sun-1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Sun-1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Sun-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Post Sun &ndash; Clean Minimum Animated IG Social Media Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-story-mint-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-story-Mint-1-1024x683.jpg\" alt=\"Instagram Template Canva Story Mint - Modern Retro Social Media Branding Animated Pack - Quotes, Notification, CTA\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-story-Mint-1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-story-Mint-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-story-Mint-1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-story-Mint-1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-story-Mint-1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-story-Mint-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Story Mint &ndash; Modern Retro Social Media Branding Animated Pack &ndash; Quotes, Notification, CTA<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-story-templates-canva-shadow-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-story-templates-canva-shadow.jpg\" alt=\"\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-story-templates-canva-shadow.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-story-templates-canva-shadow-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-story-templates-canva-shadow-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-story-templates-canva-shadow.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Story Templates Canva Shadow<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-post-templates-canva-sales-phrase-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-sales-phrase-templates-canva-1.jpg\" alt=\"&#12471;&#12531;&#12503;&#12523;&#12362;&#12375;&#12419;&#12428;&#12394;&#12452;&#12531;&#12473;&#12479;&#12464;&#12521;&#12512;&#12475;&#12540;&#12523;&#25237;&#31295;&#12486;&#12531;&#12503;&#12524;&#12540;&#12488;Canva100&#28857;&#12475;&#12483;&#12488;\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-sales-phrase-templates-canva-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-sales-phrase-templates-canva-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-sales-phrase-templates-canva-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-sales-phrase-templates-canva-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">100 Instagram Sales Phrase Templates Canva &ndash; Editable Engaging Social Media Post Creator Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-story-templates-canva-calendar-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Calendar-Story-Templates-animated1.jpg\" alt=\"\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Calendar-Story-Templates-animated1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Calendar-Story-Templates-animated1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Calendar-Story-Templates-animated1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Calendar-Story-Templates-animated1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram 96 Advent Calendar Story Templates Canva &ndash; Editable Minimum Social Media Pinterest Branding Creator Pack &ndash; Countdown Journal Diary<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-mint-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Mint-1-1024x683.jpg\" alt=\"Instagram Template Canva Post Mint - Clean Minimum Animated Modern Retro Social Media Pack\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Mint-1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Mint-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Mint-1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Mint-1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Mint-1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Mint-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Post Mint &ndash; Clean Minimum Animated Modern Retro Social Media Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/boho-sales-promo-instagram-templates-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-boho-13.jpg\" alt=\"Instagram Template Canva Post Story Portrait - Elegant Minimum Boho Sales Promotion Social Media IG Pack\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-boho-13.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-boho-13-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-boho-13-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-boho-13.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Boho Sales Promo Instagram Templates Canva &ndash; customizable editable elegant posts stories<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-stories-templates-brown-beige-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-Instagram-Story-Template-Canva-Editable-Clean-Minimum-Beige-Brown-Carousel-IG-Social-Media-Post-Pack.jpg\" alt=\"\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-Instagram-Story-Template-Canva-Editable-Clean-Minimum-Beige-Brown-Carousel-IG-Social-Media-Post-Pack.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-Instagram-Story-Template-Canva-Editable-Clean-Minimum-Beige-Brown-Carousel-IG-Social-Media-Post-Pack-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-Instagram-Story-Template-Canva-Editable-Clean-Minimum-Beige-Brown-Carousel-IG-Social-Media-Post-Pack-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-Instagram-Story-Template-Canva-Editable-Clean-Minimum-Beige-Brown-Carousel-IG-Social-Media-Post-Pack.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Story Reel Template Canva &ndash; Editable Clean Minimum Beige Brown Carousel IG Social Media Post Pack &ndash; Quotes, Notification, CTA<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-shadow-a-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-1-1024x683.jpg\" alt=\"Instagram Template Canva Carousel Post Shadow A - Clean Minimum Animated IG Social Media Pack\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Carousel Post Shadow A &ndash; Clean Minimum Animated IG Social Media Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-post-templates-canva-tracing-paper-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Templates-Canva-Dot-2.jpg\" alt=\"\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Templates-Canva-Dot-2.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Templates-Canva-Dot-2-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Templates-Canva-Dot-2-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Post-Templates-Canva-Dot-2.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">100 Instagram Templates Canva Post Dot- Editable Pink Beige Social Media Branding Post Creator Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-post-templates-carousel-zen-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-templates-canva-editable-carousel-social-media-design-engagement-content-marketing1.jpg\" alt=\"\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-templates-canva-editable-carousel-social-media-design-engagement-content-marketing1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-templates-canva-editable-carousel-social-media-design-engagement-content-marketing1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-templates-canva-editable-carousel-social-media-design-engagement-content-marketing1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-templates-canva-editable-carousel-social-media-design-engagement-content-marketing1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Post Templates Canva Zen &ndash; Editable Minimum Blue Gray Carousel Contents Marketing IG Social Media CTA Feed Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-story-wabi-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/300-Instagram-Template-Canva-Bundle-1.jpg\" alt=\"300 Instagram Template Canva Bundle - Carousel Post Portrait Story Reel Shorts Animated Social Media\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/300-Instagram-Template-Canva-Bundle-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/300-Instagram-Template-Canva-Bundle-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/300-Instagram-Template-Canva-Bundle-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/300-Instagram-Template-Canva-Bundle-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">300 Instagram Template Canva Bundle &ndash; Carousel Post Portrait Story Reel Shorts Animated Social Media<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-post-templates-canva-calendar-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Calendar-Post-Templates-animated-1.jpg\" alt=\"Instagram Calendar Post Templates\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Calendar-Post-Templates-animated-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Calendar-Post-Templates-animated-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Calendar-Post-Templates-animated-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Calendar-Post-Templates-animated-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram 96 Advent Calendar Post Templates Canva &ndash; Editable Minimum Carousel Social Media Branding Creator Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-template-canva-story-zen-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Story-Zen1.jpg\" alt=\"\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Story-Zen1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Story-Zen1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Story-Zen1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Story-Zen1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Story Zen &ndash; Clean Minimum Social Media Pinterest Branding Animated Creator Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-story-templates-canva-tracing-paper-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-100-story-animation-Bundle-Canva1.jpg\" alt=\"&#12452;&#12531;&#12473;&#12479;&#12464;&#12521;&#12512;&#12473;&#12488;&#12540;&#12522;&#12540;&#12486;&#12531;&#12503;&#12524;&#12540;&#12488;Canva100&#28857;&#12475;&#12483;&#12488; - &#12488;&#12524;&#12540;&#12471;&#12531;&#12464;&#12506;&#12540;&#12497;&#12540;\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-100-story-animation-Bundle-Canva1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-100-story-animation-Bundle-Canva1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-100-story-animation-Bundle-Canva1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-100-story-animation-Bundle-Canva1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Story Templates Canva Dot &ndash; Editable Pink Beige Social Media Pinterest Branding Animated Creator Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-post-templates-brown-beige-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-Instagram-template-Canva.jpg\" alt=\"\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-Instagram-template-Canva.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-Instagram-template-Canva-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-Instagram-template-Canva-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-Instagram-template-Canva.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram template Canva &ndash; Customizable Editable Clean Minimum Beige Brown Carousel IG Social Media Post Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-shadow-b-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-2-1024x683.jpg\" alt=\"Instagram Template Canva Carousel Post Shadow B - Clean Minimum Animated IG Social Media Pack\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-2-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-2-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-2-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-2-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-2.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Carousel-Post-2.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Carousel Post Shadow B &ndash; Clean Minimum Animated IG Social Media Pack&#65532;<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/sales-promo-instagram-templates-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-sales-promo-instagram-templates.jpg\" alt=\"&#12452;&#12531;&#12473;&#12479;&#25237;&#31295;&amp;&#12473;&#12488;&#12540;&#12522;&#12540;&#12474;&#23550;&#24540;&#12475;&#12540;&#12523;&#12473;&#12503;&#12525;&#12514;&#12540;&#12471;&#12519;&#12531;&#12486;&#12531;&#12503;&#12524;&#12540;&#12488; for Canva\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-sales-promo-instagram-templates.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-sales-promo-instagram-templates-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-sales-promo-instagram-templates-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/1-sales-promo-instagram-templates.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva &ndash; Elegant Minimum Sales Promotion Organic Post Story Portrait Creator Retail, Boutique, Blogger<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-post-shine-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Shine-1-1.jpg\" alt=\"Instagram Template Canva Post Shine - Clean Minimum Carousel IG Social Media Pack - Quotes, Notification, CTA\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Shine-1-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Shine-1-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Shine-1-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Shine-1-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Post Shine &ndash; Clean Minimum Carousel IG Social Media Pack &ndash; Quotes, Notification, CTA<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-story-shine-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Story-Shine-1-1.jpg\" alt=\"Instagram Template Canva Story Shine\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Story-Shine-1-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Story-Shine-1-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Story-Shine-1-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Story-Shine-1-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Story Shine &ndash; Social Media Pinterest Branding Animated Creator Pack &ndash; Quotes, Notification, CTA<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-post-templates-canva-shadow-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-templates-canva-shadow.jpg\" alt=\"&#12452;&#12531;&#12473;&#12479;&#12464;&#12521;&#12512;&#27491;&#26041;&#24418;&#12486;&#12531;&#12503;&#12524;&#12540;&#12488;Canva Shadow\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-templates-canva-shadow.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-templates-canva-shadow-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-templates-canva-shadow-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/instagram-post-templates-canva-shadow.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Post Shadow &ndash; Editable Clean Design Social Media Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/instagram-templates-canva-retro-summer-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Game-1.jpg\" alt=\"Instagram Template Canva Post Game - Retro Summer Fun Cute Photo Frame Social Media\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Game-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Game-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Game-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-Template-Canva-Post-Game-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Instagram Template Canva Post Game &ndash; Retro Summer Fun Cute Photo Frame Social Media<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<\/ul><\/div>\n\n\n<div class=\"swell-block-button red_ is-style-btn_shiny u-mb-ctrl u-mb-30\" data-id=\"4316b78e\"><a href=\"https:\/\/keikoya.gumroad.com\/l\/WholeShopBundle?a=389461075\" target=\"_blank\" rel=\"noopener nofollow\" class=\"swell-block-button__link\" data-has-icon=\"1\"><span>BUY DEAL NOW<\/span><svg class=\"__icon -right\" height=\"1em\" width=\"1em\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" viewbox=\"0 0 448 512\"><path d=\"M438.6 278.6c12.5-12.5 12.5-32.8 0-45.3l-160-160c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3L338.8 224 32 224c-17.7 0-32 14.3-32 32s14.3 32 32 32l306.7 0L233.4 393.4c-12.5 12.5-12.5 32.8 0 45.3s32.8 12.5 45.3 0l160-160z\"><\/path><\/svg><\/a><\/div>\n\n\n\n<h3 class=\"wp-block-heading is-style-section_ttl\">Ebook Templates<\/h3>\n\n\n<div class=\"p-postListWrap\"><ul class=\"p-postList -type-card -pc-col3 -sp-col1\"><li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/a4-letter-templates-canva-shadow-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/a4-letter-templates-canva-shadow-1.jpg\" alt=\"\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/a4-letter-templates-canva-shadow-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/a4-letter-templates-canva-shadow-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/a4-letter-templates-canva-shadow-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/a4-letter-templates-canva-shadow-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">60 eBook Template Canva Shadow &ndash; A4 &amp; US Letter Magazine Design Cover Lead magnet Coaching Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/a4-letter-templates-canva-dot-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Porka-Dot-1.jpg\" alt=\"eBook Template Canva Polka Dot\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Porka-Dot-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Porka-Dot-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Porka-Dot-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Porka-Dot-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">72 eBook Templates Canva Polka Dot &ndash; A4 US Letter Magazine Design Cover Lead magnet Coaching Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/a4-letter-templates-canva-beige-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Beige-1.jpg\" alt=\"eBook Template Canva Beige - A4 US Letter Magazine Design Cover Lead magnet Coaching Pack\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Beige-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Beige-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Beige-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Beige-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">eBook Template Canva Beige &ndash; A4 US Letter Magazine Design Cover Lead magnet Coaching Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/a4-letter-templates-canva-calendar-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Calendar-1.jpg\" alt=\"eBook Template Canva Calendar - A4 US Letter Magazine Design Cover Lead magnet Coaching Pack\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Calendar-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Calendar-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Calendar-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/eBook-Template-Canva-Calendar-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">76 eBook Templates Canva Calendar &ndash; A4 US Letter Magazine Design Cover Lead Magnet Coaching Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<\/ul><\/div>\n\n\n<h4 class=\"wp-block-heading is-style-section_ttl\">Pinterest Templates<\/h4>\n\n\n<div class=\"p-postListWrap\"><ul class=\"p-postList -type-card -pc-col3 -sp-col1\"><li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/pinterest-pin-templates-canva-shadow-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/pinterest-pin-templates-canva-shadow-1.jpg\" alt=\"&#12500;&#12531;&#12479;&#12524;&#12473;&#12488;Canva&#12486;&#12531;&#12503;&#12524;&#12540;&#12488;&#12304;&#12450;&#12491;&#12513;&#12540;&#12471;&#12519;&#12531;&amp;&#35079;&#25968;&#30011;&#20687;&#25237;&#31295;&#12487;&#12470;&#12452;&#12531;&#23550;&#24540;&#12305;\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/pinterest-pin-templates-canva-shadow-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/pinterest-pin-templates-canva-shadow-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/pinterest-pin-templates-canva-shadow-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/pinterest-pin-templates-canva-shadow-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Pinterest Pin Templates Canva Shadow<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/pinterest-templates-canva-mint-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Mint-1-1024x683.jpg\" alt=\"Pinterest Templates Canva Mint - Modern Retro Customizable Minimum Social Media Contents Marketing Design Pack\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Mint-1-1024x683.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Mint-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Mint-1-768x512.jpg 768w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Mint-1-1536x1025.jpg 1536w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Mint-1.jpg 2048w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Mint-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Pinterest Templates Canva Mint &ndash; Modern Retro Customizable Minimum Social Media Contents Marketing Design Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/pinterest-templates-canva-wabi-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Wabi-Sabi-1.jpg\" alt=\"Pinterest Templates Canva Wabi Sabi - Customizable Clean Minimum Social Media Contents Marketing Design Pack\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Wabi-Sabi-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Wabi-Sabi-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Wabi-Sabi-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Pinterest-Templates-Canva-Wabi-Sabi-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<div class=\"p-postList__title\">Pinterest Templates Canva Wabi Sabi &ndash; Customizable Clean Minimum Social Media Contents Marketing Design Pack<\/div>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<\/ul><\/div>\n\n\n<div class=\"swell-block-button red_ is-style-btn_shiny u-mb-ctrl u-mb-30\" data-id=\"45291636\"><a href=\"https:\/\/keikoya.gumroad.com\/l\/WholeShopBundle?a=389461075\" target=\"_blank\" rel=\"noopener nofollow\" class=\"swell-block-button__link\" data-has-icon=\"1\"><span>BUY DEAL NOW<\/span><svg class=\"__icon -right\" height=\"1em\" width=\"1em\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" viewbox=\"0 0 448 512\"><path d=\"M438.6 278.6c12.5-12.5 12.5-32.8 0-45.3l-160-160c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3L338.8 224 32 224c-17.7 0-32 14.3-32 32s14.3 32 32 32l306.7 0L233.4 393.4c-12.5 12.5-12.5 32.8 0 45.3s32.8 12.5 45.3 0l160-160z\"><\/path><\/svg><\/a><\/div>\n\n\n\n<h3 class=\"wp-block-heading is-style-section_ttl\">Canva Photo Frames<\/h3>\n\n\n<div class=\"p-postListWrap\"><ul class=\"p-postList -type-card -pc-col3 -sp-col1\"><li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/cherry-blossom-photo-frames-canva-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/2dfa317d9a1ab95bfb406335b0fafc44.jpg\" alt=\"12 Cherry Blossom Photo Frames for Canva\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/2dfa317d9a1ab95bfb406335b0fafc44.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/2dfa317d9a1ab95bfb406335b0fafc44-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/2dfa317d9a1ab95bfb406335b0fafc44-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/2dfa317d9a1ab95bfb406335b0fafc44.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<h2 class=\"p-postList__title\">12 Cherry Blossom Photo Frames for Canva<\/h2>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/rounded-square-photo-frames-canva-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/8d6d70e5cfd7c818fb1a8f59ea27d061.jpg\" alt=\"18 Rounded Square Photo Frames for Canva\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/8d6d70e5cfd7c818fb1a8f59ea27d061.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/8d6d70e5cfd7c818fb1a8f59ea27d061-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/8d6d70e5cfd7c818fb1a8f59ea27d061-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/8d6d70e5cfd7c818fb1a8f59ea27d061.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<h2 class=\"p-postList__title\">18 Rounded Square Photo Frames for Canva<\/h2>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/semicircle-photo-frames-canva-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/72-Semicircle-Photo-Frames-Canva-thumbnail.jpg\" alt=\"72 Semicircle Photo Frames + 36 Combinations for Canva\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/72-Semicircle-Photo-Frames-Canva-thumbnail.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/72-Semicircle-Photo-Frames-Canva-thumbnail-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/72-Semicircle-Photo-Frames-Canva-thumbnail-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/72-Semicircle-Photo-Frames-Canva-thumbnail.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<h2 class=\"p-postList__title\">72 Semicircle Photo Frames + 36 Combinations for Canva<\/h2>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/right-triangle-photo-frames-canva-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/72-right-triangle-photo-frames-canva-blog.jpg\" alt=\"72 Right Triangle Photo Frames + 54 Combinations for Canva\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/72-right-triangle-photo-frames-canva-blog.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/72-right-triangle-photo-frames-canva-blog-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/72-right-triangle-photo-frames-canva-blog-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/72-right-triangle-photo-frames-canva-blog.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<h2 class=\"p-postList__title\">72 Right Triangle Photo Frames + 54 Combinations for Canva<\/h2>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/rounded-rectangle-photo-frames-for-canva-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/36-rounded-rectangle-photo-frames-Canva-blog.jpg\" alt=\"36 Rounded Rectangle Photo Frames for Canva\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/36-rounded-rectangle-photo-frames-Canva-blog.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/36-rounded-rectangle-photo-frames-Canva-blog-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/36-rounded-rectangle-photo-frames-Canva-blog-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/36-rounded-rectangle-photo-frames-Canva-blog.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<h2 class=\"p-postList__title\">36 Rounded Rectangle Photo Frames for Canva<\/h2>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/19-heart-photo-frames-for-canva\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/19-Heart-Photo-Frames-cover.jpg\" alt=\"19 Heart Photo Frames for Canva\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/19-Heart-Photo-Frames-cover.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/19-Heart-Photo-Frames-cover-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/19-Heart-Photo-Frames-cover-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/19-Heart-Photo-Frames-cover.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<h2 class=\"p-postList__title\">19 Heart Photo Frames for Canva<\/h2>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<\/ul><\/div>\n\n\n<h3 class=\"wp-block-heading is-style-section_ttl\">Other Design Resources<\/h3>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/kmy.website\/multilingual-food-menu-templates-sample\/\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Multilingual-Food-Menu-Templates1.jpg\" alt=\"\" class=\"wp-image-33650\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Multilingual-Food-Menu-Templates1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Multilingual-Food-Menu-Templates1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Multilingual-Food-Menu-Templates1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Multilingual-Food-Menu-Templates1.jpg\"><\/a><figcaption class=\"wp-element-caption\">Multilingual Food Menu Templates<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/kmy.website\/retro-game-social-media-pack\/\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/retro-game-SOCIAL-MEDIA-PACK-title.jpg\" alt=\"&#12461;&#12483;&#12481;&#12517;&#12391;&#12363;&#12431;&#12356;&#12356;&#12524;&#12488;&#12525;&#12466;&#12540;&#12512;&#39080; SOCIAL MEDIA PACK\" class=\"wp-image-33878\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/retro-game-SOCIAL-MEDIA-PACK-title.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/retro-game-SOCIAL-MEDIA-PACK-title-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/retro-game-SOCIAL-MEDIA-PACK-title-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/retro-game-SOCIAL-MEDIA-PACK-title.jpg\"><\/a><figcaption class=\"wp-element-caption\">&#12461;&#12483;&#12481;&#12517;&#12391;&#12363;&#12431;&#12356;&#12356;&#12524;&#12488;&#12525;&#12466;&#12540;&#12512;&#39080; <br>SOCIAL MEDIA PACK<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/kmy.website\/instagram-story-reel-template-jp\/\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-story-reel-template-jp-thumbnail.jpg\" alt=\"&#12452;&#12531;&#12473;&#12479;&#12463;&#12441;&#12521;&#12512;&#12473;&#12488;&#12540;&#12522;&#12540;&amp;&#12522;&#12540;&#12523;&#12459;&#12495;&#12441;&#12540;&#12486;&#12531;&#12501;&#12442;&#12524;&#12540;&#12488;&#38598;Canva\" class=\"wp-image-35074\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-story-reel-template-jp-thumbnail.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-story-reel-template-jp-thumbnail-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-story-reel-template-jp-thumbnail-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Instagram-story-reel-template-jp-thumbnail.jpg\"><\/a><figcaption class=\"wp-element-caption\">&#12452;&#12531;&#12473;&#12479;&#12464;&#12521;&#12512;&#12473;&#12488;&#12540;&#12522;&#12540;&amp;&#12522;&#12540;&#12523;&#12459;&#12496;&#12540;&#12486;&#12531;&#12503;&#12524;&#12540;&#12488;&#38598;<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n<div class=\"p-postListWrap\"><ul class=\"p-postList -type-card -pc-col3 -sp-col1\"><li class=\"p-postList__item\">\n\t<a href=\"https:\/\/kmy.website\/en\/photo-overlay-polka-dot-en\/\" class=\"p-postList__link\">\n\t\t<div class=\"p-postList__thumb c-postThumb\">\n\t<figure class=\"c-postThumb__figure\">\n\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Polka-Dot-Overlay-translucent-pattern-background-1.jpg\" alt=\"\" class=\"c-postThumb__img u-obf-cover\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Polka-Dot-Overlay-translucent-pattern-background-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Polka-Dot-Overlay-translucent-pattern-background-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/Polka-Dot-Overlay-translucent-pattern-background-1-768x512.jpg 768w\" sizes=\"auto, (min-width: 960px) 400px, 100vw\" loading=\"lazy\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/Polka-Dot-Overlay-translucent-pattern-background-1.jpg\">\t<\/figure>\n\t<\/div>\n\t\t\t\t\t<div class=\"p-postList__body\">\n\t\t\t\t<h2 class=\"p-postList__title\">Polka Dot Translucent Photo Overlays<\/h2>\t\t\t\t\t\t\t\t<div class=\"p-postList__meta\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/a>\n<\/li>\n<\/ul><\/div>\n\n\n<div class=\"swell-block-button red_ is-style-btn_shiny\" data-id=\"31497dce\"><a href=\"https:\/\/keikoya.gumroad.com\/l\/WholeShopBundle?a=389461075\" target=\"_blank\" rel=\"noopener nofollow\" class=\"swell-block-button__link\" data-has-icon=\"1\"><span>BUY DEAL NOW<\/span><svg class=\"__icon -right\" height=\"1em\" width=\"1em\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" viewbox=\"0 0 448 512\"><path d=\"M438.6 278.6c12.5-12.5 12.5-32.8 0-45.3l-160-160c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3L338.8 224 32 224c-17.7 0-32 14.3-32 32s14.3 32 32 32l306.7 0L233.4 393.4c-12.5 12.5-12.5 32.8 0 45.3s32.8 12.5 45.3 0l160-160z\"><\/path><\/svg><\/a><\/div>\n\n\n<div class=\"p-blogParts post_content\" data-partsid=\"49794\">\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center is-style-balloon_box2 wp-block-paragraph\"><strong>Customer Reviews that Speak Volumes<\/strong><\/p>\n\n\n\n<script type=\"text\/javascript\" src=\"https:\/\/testimonial.to\/js\/iframeResizer.min.js\"><\/script>\n<iframe id=\"testimonialto-keikoya-testimonial-tag-all-light\" src=\"https:\/\/embed-v2.testimonial.to\/w\/keikoya-testimonial?theme=light&amp;card=base&amp;loadMore=on&amp;initialCount=20&amp;hideDate=on&amp;tag=all\" frameborder=\"0\" scrolling=\"no\" width=\"100%\"><\/iframe>\n<script type=\"text\/javascript\">iFrameResize({log: false, checkOrigin: false}, \"#testimonialto-keikoya-testimonial-tag-all-light\");<\/script>\n<\/div>\n\n<div class=\"p-blogParts post_content\" data-partsid=\"34004\">\n<p class=\"wp-block-paragraph\">For more information on how to use Tsukuru Depot original design materials, please read the <a href=\"https:\/\/kmy.website\/termsofuse\/\">Terms of Use<\/a>.<\/p>\n<\/div>\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/keikoya-whole-shop-design-bundle-over-3800-templates-canva-free-updates-1.jpg\" alt=\"Keikoya whole shop design bundle\" class=\"wp-image-42238\" srcset=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/keikoya-whole-shop-design-bundle-over-3800-templates-canva-free-updates-1.jpg 1024w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/keikoya-whole-shop-design-bundle-over-3800-templates-canva-free-updates-1-300x200.jpg 300w, https:\/\/kmy.website\/blog\/wp-content\/uploads\/keikoya-whole-shop-design-bundle-over-3800-templates-canva-free-updates-1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-pin-media=\"https:\/\/kmy.website\/blog\/wp-content\/uploads\/keikoya-whole-shop-design-bundle-over-3800-templates-canva-free-updates-1.jpg\"><\/figure>\n\n\n\n<div class=\"swell-block-button red_ is-style-btn_shiny\" data-id=\"1c019ef5\"><a href=\"https:\/\/keikoya.gumroad.com\/l\/WholeShopBundle?a=389461075\" target=\"_blank\" rel=\"noopener nofollow\" class=\"swell-block-button__link\" data-has-icon=\"1\"><span>BUY DEAL NOW<\/span><svg class=\"__icon -right\" height=\"1em\" width=\"1em\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" viewbox=\"0 0 448 512\"><path d=\"M438.6 278.6c12.5-12.5 12.5-32.8 0-45.3l-160-160c-12.5-12.5-32.8-12.5-45.3 0s-12.5 32.8 0 45.3L338.8 224 32 224c-17.7 0-32 14.3-32 32s14.3 32 32 32l306.7 0L233.4 393.4c-12.5 12.5-12.5 32.8 0 45.3s32.8 12.5 45.3 0l160-160z\"><\/path><\/svg><\/a><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-pinterest wp-block-embed-pinterest\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Keikoya Whole Shop Design Bundle - 3800+ Canva Templates &amp; Free Update\" src=\"https:\/\/assets.pinterest.com\/ext\/embed.html?id=340444053093521881&amp;src=oembed\" height=\"899\" width=\"450\" frameborder=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">&#9650; Save it on Pinterest<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Keikoya Whole Shop Design Bundle &ndash; 3800+ Canva Templates &amp; Free Update Get&nbsp;over $900 worth&#038;nbsp [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"swell_btn_cv_data":"{\"c4c93406\":{\"pv\":729,\"imp\":542,\"click\":50},\"31497dce\":{\"pv\":729,\"imp\":37,\"click\":1},\"b439fd60\":{\"pv\":97,\"imp\":35,\"click\":3},\"4316b78e\":{\"pv\":97,\"imp\":13},\"1c019ef5\":{\"pv\":97,\"imp\":4,\"click\":1},\"45291636\":{\"pv\":77,\"imp\":4}}","_locale":"en_US","_original_post":"https:\/\/kmy.website\/?p=42032","footnotes":"","_wp_rev_ctl_limit":"10"},"categories":[199],"tags":[216],"class_list":["post-42034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-template","tag-featured-items","en-US"],"_links":{"self":[{"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/posts\/42034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/comments?post=42034"}],"version-history":[{"count":10,"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/posts\/42034\/revisions"}],"predecessor-version":[{"id":49867,"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/posts\/42034\/revisions\/49867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/media\/42238"}],"wp:attachment":[{"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/media?parent=42034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/categories?post=42034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kmy.website\/wp-json\/wp\/v2\/tags?post=42034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}